{"id":17887,"date":"2026-03-10T11:39:29","date_gmt":"2026-03-10T11:39:29","guid":{"rendered":"https:\/\/despensafranciscana.com\/?p=17887"},"modified":"2026-03-10T14:36:53","modified_gmt":"2026-03-10T14:36:53","slug":"cheesecake-franciscano","status":"publish","type":"post","link":"https:\/\/despensafranciscana.com\/de\/2026\/03\/10\/cheesecake-franciscano\/","title":{"rendered":"Cheesecake Franciscano"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-0\"><div class=\"row limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div class=\"uncode_text_column\" ><\/p>\n<h2>Inhaltsstoffe<\/h2>\n<h3>Base:<\/h3>\n<p>&#8211; 150g bolacha aveia e ginja<br \/>\n&#8211; 100g de manteiga derretida<\/p>\n<h3>Creme:<\/h3>\n<p>&#8211; 250g requeij\u00e3o<br \/>\n&#8211; 200ml natas bem frescas para bater<br \/>\n&#8211; 100g a\u00e7\u00facar<br \/>\n&#8211; 7 folhas de gelatina<\/p>\n<h3>Cobertura:<\/h3>\n<p>&#8211; 200g morangos e ginjas descaro\u00e7adas<br \/>\n&#8211; 1 c\u00e1lice de ginja Franciscana<br \/>\n&#8211; 3 colheres de sopa de a\u00e7\u00facar<br \/>\n&#8211; Raspas de 1 lim\u00e3o<br \/>\n&#8211; Ess\u00eancia de baunilha<\/p>\n<\/div><div class=\"uncode_text_column\" ><\/p>\n<h2>Modo prepara\u00e7\u00e3o<\/h2>\n<h3>Base:<\/h3>\n<p>Comece por derreter a manteiga e triturar as bolachas .<br \/>\nDe seguida misture tudo e coloque no fundo de uma forma amov\u00edvel pressionando bem para criar a base do nosso cheesecake e de seguida reserve no frigor\u00edfico.<\/p>\n<h3>Calda:<\/h3>\n<p>Para a nossa calda, coloque numa frigideira os morangos e as ginjas, o a\u00e7\u00facar, as raspas de lim\u00e3o, um c\u00e1lice ginja e uma colher de ch\u00e1 de ess\u00eancia de baunilha e deixe reduzir durante uns minutos.<br \/>\nTriture e adicione as folhas de gelatina para finalizar.<\/p>\n<h3>Creme:<\/h3>\n<p>Bata o requeij\u00e3o com o a\u00e7\u00facar, adicione as folhas de gelatina e misture at\u00e9 criar um creme.<br \/>\nDe seguida, junte as natas, previamente batidas, ao creme e misture delicadamente. Deite o creme por cima da bolacha e reserve novamente no frio durante 30 minutos .<\/p>\n<p>Finalize com a calda por cima e deixe por 3 horas no frigor\u00edfico antes de servir .<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-0\" data-row=\"script-row-unique-0\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-0\"));<\/script><\/div><\/div><\/div><div data-parent=\"true\" class=\"vc_row row-container\" id=\"row-unique-1\"><div class=\"row limit-width row-parent\"><div class=\"wpb_row row-inner\"><div class=\"wpb_column pos-top pos-center align_left column_parent col-lg-12 single-internal-gutter\"><div class=\"uncol style-light\"  ><div class=\"uncoltable\"><div class=\"uncell no-block-padding\" ><div class=\"uncont\" ><div id=\"gallery-164695\" class=\"un-media-gallery isotope-system isotope-general-light grid-general-light\">\n\t\t\t\t\t\n\t\n\t<div class=\"isotope-wrapper grid-wrapper single-gutter\" >\n\t\t\t\t\t\t\t\t\t<div class=\"isotope-container isotope-layout style-masonry\" data-type=\"masonry\" data-layout=\"masonry\" data-lg=\"1000\" data-md=\"600\" data-sm=\"480\">\n<div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-17891  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 150%;\"><\/div><a href=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02645.jpg\"  class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-164695\" data-external-thumb-image=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02645-150x150.jpg\" data-lg-size=\"1080-1620\" data-lb-index=\"0\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-17891\" src=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02645.jpg\" width=\"1080\" height=\"1620\" alt=\"\" srcset=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02645.jpg 1080w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02645-200x300.jpg 200w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02645-683x1024.jpg 683w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02645-768x1152.jpg 768w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02645-1024x1536.jpg 1024w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02645-8x12.jpg 8w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02645-350x525.jpg 350w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02645-800x1200.jpg 800w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-17890  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 66.7%;\"><\/div><a href=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02640.jpg\"  class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-164695\" data-external-thumb-image=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02640-150x150.jpg\" data-lg-size=\"1080-720\" data-lb-index=\"1\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-17890\" src=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02640.jpg\" width=\"1080\" height=\"720\" alt=\"\" srcset=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02640.jpg 1080w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02640-300x200.jpg 300w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02640-1024x683.jpg 1024w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02640-768x512.jpg 768w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02640-18x12.jpg 18w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02640-350x233.jpg 350w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02640-800x533.jpg 800w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-17892  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 150%;\"><\/div><a href=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02656.jpg\"  class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-164695\" data-external-thumb-image=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02656-150x150.jpg\" data-lg-size=\"1080-1620\" data-lb-index=\"2\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-17892\" src=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02656.jpg\" width=\"1080\" height=\"1620\" alt=\"\" srcset=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02656.jpg 1080w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02656-200x300.jpg 200w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02656-683x1024.jpg 683w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02656-768x1152.jpg 768w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02656-1024x1536.jpg 1024w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02656-8x12.jpg 8w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02656-350x525.jpg 350w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02656-800x1200.jpg 800w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-17894  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 150%;\"><\/div><a href=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02681.jpg\"  class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-164695\" data-external-thumb-image=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02681-150x150.jpg\" data-lg-size=\"1080-1620\" data-lb-index=\"3\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-17894\" src=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02681.jpg\" width=\"1080\" height=\"1620\" alt=\"\" srcset=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02681.jpg 1080w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02681-200x300.jpg 200w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02681-683x1024.jpg 683w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02681-768x1152.jpg 768w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02681-1024x1536.jpg 1024w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02681-8x12.jpg 8w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02681-350x525.jpg 350w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/DSC02681-800x1200.jpg 800w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"tmb tmb-iso-w4 tmb-iso-h4 tmb-light tmb-overlay-text-anim tmb-overlay-anim tmb-overlay-middle tmb-overlay-text-left tmb-image-anim tmb-bordered tmb-id-17889  tmb-media-first tmb-media-last tmb-content-overlay tmb-no-bg tmb-lightbox\" ><div class=\"t-inside no-anim\" ><div class=\"t-entry-visual\"><div class=\"t-entry-visual-tc\"><div class=\"t-entry-visual-cont\"><div class=\"dummy\" style=\"padding-top: 150%;\"><\/div><a href=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b.jpg\"  class=\"pushed\" data-active=\"1\" data-lbox=\"ilightbox_gallery-164695\" data-external-thumb-image=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b-150x150.jpg\" data-lg-size=\"1013-1520\" data-lb-index=\"4\"><div class=\"t-entry-visual-overlay\"><div class=\"t-entry-visual-overlay-in style-dark-bg\" style=\"opacity: 0.5;\"><\/div><\/div><img decoding=\"async\" class=\"wp-image-17889\" src=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b.jpg\" width=\"1013\" height=\"1520\" alt=\"\" srcset=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b.jpg 1013w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b-200x300.jpg 200w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b-682x1024.jpg 682w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b-768x1152.jpg 768w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b-8x12.jpg 8w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b-350x525.jpg 350w, https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b-800x1200.jpg 800w\" sizes=\"(max-width: 1013px) 100vw, 1013px\" \/><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\t\n\t\n<\/div>\n\n<\/div><\/div><\/div><\/div><\/div><script id=\"script-row-unique-1\" data-row=\"script-row-unique-1\" type=\"text\/javascript\" class=\"vc_controls\">UNCODE.initRow(document.getElementById(\"row-unique-1\"));<\/script><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Ingredientes Base: &#8211; 150g bolacha aveia e ginja &#8211; 100g de manteiga derretida Creme: &#8211; 250g requeij\u00e3o &#8211; 200ml natas [...]","protected":false},"author":98,"featured_media":17889,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[],"class_list":["post-17887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-receitas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cheesecake Franciscano - Despensa Franciscana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/despensafranciscana.com\/de\/2026\/03\/10\/cheesecake-franciscano\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cheesecake Franciscano - Despensa Franciscana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/despensafranciscana.com\/de\/2026\/03\/10\/cheesecake-franciscano\/\" \/>\n<meta property=\"og:site_name\" content=\"Despensa Franciscana\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/despensafranciscana\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-10T11:39:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-10T14:36:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1013\" \/>\n\t<meta property=\"og:image:height\" content=\"1520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"BOLEIMA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"BOLEIMA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/2026\\\/03\\\/10\\\/cheesecake-franciscano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/2026\\\/03\\\/10\\\/cheesecake-franciscano\\\/\"},\"author\":{\"name\":\"BOLEIMA\",\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/#\\\/schema\\\/person\\\/a9137126aeb346810a49f291d5693921\"},\"headline\":\"Cheesecake Franciscano\",\"datePublished\":\"2026-03-10T11:39:29+00:00\",\"dateModified\":\"2026-03-10T14:36:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/2026\\\/03\\\/10\\\/cheesecake-franciscano\\\/\"},\"wordCount\":272,\"publisher\":{\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/2026\\\/03\\\/10\\\/cheesecake-franciscano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/despensafranciscana.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b.jpg\",\"articleSection\":[\"Receitas\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/2026\\\/03\\\/10\\\/cheesecake-franciscano\\\/\",\"url\":\"https:\\\/\\\/despensafranciscana.com\\\/2026\\\/03\\\/10\\\/cheesecake-franciscano\\\/\",\"name\":\"Cheesecake Franciscano - Despensa Franciscana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/2026\\\/03\\\/10\\\/cheesecake-franciscano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/2026\\\/03\\\/10\\\/cheesecake-franciscano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/despensafranciscana.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b.jpg\",\"datePublished\":\"2026-03-10T11:39:29+00:00\",\"dateModified\":\"2026-03-10T14:36:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/2026\\\/03\\\/10\\\/cheesecake-franciscano\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/despensafranciscana.com\\\/2026\\\/03\\\/10\\\/cheesecake-franciscano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/2026\\\/03\\\/10\\\/cheesecake-franciscano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/despensafranciscana.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b.jpg\",\"contentUrl\":\"https:\\\/\\\/despensafranciscana.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b.jpg\",\"width\":1013,\"height\":1520},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/2026\\\/03\\\/10\\\/cheesecake-franciscano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/despensafranciscana.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cheesecake Franciscano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/#website\",\"url\":\"https:\\\/\\\/despensafranciscana.com\\\/\",\"name\":\"Despensa Franciscana\",\"description\":\"Despensa Franciscana\",\"publisher\":{\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/despensafranciscana.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/#organization\",\"name\":\"Despensa Franciscana\",\"url\":\"https:\\\/\\\/despensafranciscana.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/despensafranciscana.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/despensa-franciscana-revamp-logos-8.png\",\"contentUrl\":\"https:\\\/\\\/despensafranciscana.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/despensa-franciscana-revamp-logos-8.png\",\"width\":1920,\"height\":628,\"caption\":\"Despensa Franciscana\"},\"image\":{\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/despensafranciscana\\\/\",\"https:\\\/\\\/www.instagram.com\\\/despensafranciscana\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/despensafranciscana.com\\\/#\\\/schema\\\/person\\\/a9137126aeb346810a49f291d5693921\",\"name\":\"BOLEIMA\",\"url\":\"https:\\\/\\\/despensafranciscana.com\\\/de\\\/author\\\/boleima\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cheesecake Franciscano - Despensa Franciscana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/despensafranciscana.com\/de\/2026\/03\/10\/cheesecake-franciscano\/","og_locale":"de_DE","og_type":"article","og_title":"Cheesecake Franciscano - Despensa Franciscana","og_url":"https:\/\/despensafranciscana.com\/de\/2026\/03\/10\/cheesecake-franciscano\/","og_site_name":"Despensa Franciscana","article_publisher":"https:\/\/www.facebook.com\/despensafranciscana\/","article_published_time":"2026-03-10T11:39:29+00:00","article_modified_time":"2026-03-10T14:36:53+00:00","og_image":[{"width":1013,"height":1520,"url":"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b.jpg","type":"image\/jpeg"}],"author":"BOLEIMA","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"BOLEIMA","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/despensafranciscana.com\/2026\/03\/10\/cheesecake-franciscano\/#article","isPartOf":{"@id":"https:\/\/despensafranciscana.com\/2026\/03\/10\/cheesecake-franciscano\/"},"author":{"name":"BOLEIMA","@id":"https:\/\/despensafranciscana.com\/#\/schema\/person\/a9137126aeb346810a49f291d5693921"},"headline":"Cheesecake Franciscano","datePublished":"2026-03-10T11:39:29+00:00","dateModified":"2026-03-10T14:36:53+00:00","mainEntityOfPage":{"@id":"https:\/\/despensafranciscana.com\/2026\/03\/10\/cheesecake-franciscano\/"},"wordCount":272,"publisher":{"@id":"https:\/\/despensafranciscana.com\/#organization"},"image":{"@id":"https:\/\/despensafranciscana.com\/2026\/03\/10\/cheesecake-franciscano\/#primaryimage"},"thumbnailUrl":"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b.jpg","articleSection":["Receitas"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/despensafranciscana.com\/2026\/03\/10\/cheesecake-franciscano\/","url":"https:\/\/despensafranciscana.com\/2026\/03\/10\/cheesecake-franciscano\/","name":"Cheesecake Franciscano - Despensa Franciscana","isPartOf":{"@id":"https:\/\/despensafranciscana.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/despensafranciscana.com\/2026\/03\/10\/cheesecake-franciscano\/#primaryimage"},"image":{"@id":"https:\/\/despensafranciscana.com\/2026\/03\/10\/cheesecake-franciscano\/#primaryimage"},"thumbnailUrl":"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b.jpg","datePublished":"2026-03-10T11:39:29+00:00","dateModified":"2026-03-10T14:36:53+00:00","breadcrumb":{"@id":"https:\/\/despensafranciscana.com\/2026\/03\/10\/cheesecake-franciscano\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/despensafranciscana.com\/2026\/03\/10\/cheesecake-franciscano\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/despensafranciscana.com\/2026\/03\/10\/cheesecake-franciscano\/#primaryimage","url":"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b.jpg","contentUrl":"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2026\/03\/c70e303a-f371-48d4-b66d-1bc0e31a0d7b.jpg","width":1013,"height":1520},{"@type":"BreadcrumbList","@id":"https:\/\/despensafranciscana.com\/2026\/03\/10\/cheesecake-franciscano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/despensafranciscana.com\/"},{"@type":"ListItem","position":2,"name":"Cheesecake Franciscano"}]},{"@type":"WebSite","@id":"https:\/\/despensafranciscana.com\/#website","url":"https:\/\/despensafranciscana.com\/","name":"Franziskanische Speisekammer","description":"Franziskanische Speisekammer","publisher":{"@id":"https:\/\/despensafranciscana.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/despensafranciscana.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/despensafranciscana.com\/#organization","name":"Franziskanische Speisekammer","url":"https:\/\/despensafranciscana.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/despensafranciscana.com\/#\/schema\/logo\/image\/","url":"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2025\/02\/despensa-franciscana-revamp-logos-8.png","contentUrl":"https:\/\/despensafranciscana.com\/wp-content\/uploads\/2025\/02\/despensa-franciscana-revamp-logos-8.png","width":1920,"height":628,"caption":"Despensa Franciscana"},"image":{"@id":"https:\/\/despensafranciscana.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/despensafranciscana\/","https:\/\/www.instagram.com\/despensafranciscana\/"]},{"@type":"Person","@id":"https:\/\/despensafranciscana.com\/#\/schema\/person\/a9137126aeb346810a49f291d5693921","name":"BOLEIMA","url":"https:\/\/despensafranciscana.com\/de\/author\/boleima\/"}]}},"_links":{"self":[{"href":"https:\/\/despensafranciscana.com\/de\/wp-json\/wp\/v2\/posts\/17887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/despensafranciscana.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/despensafranciscana.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/despensafranciscana.com\/de\/wp-json\/wp\/v2\/users\/98"}],"replies":[{"embeddable":true,"href":"https:\/\/despensafranciscana.com\/de\/wp-json\/wp\/v2\/comments?post=17887"}],"version-history":[{"count":0,"href":"https:\/\/despensafranciscana.com\/de\/wp-json\/wp\/v2\/posts\/17887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/despensafranciscana.com\/de\/wp-json\/wp\/v2\/media\/17889"}],"wp:attachment":[{"href":"https:\/\/despensafranciscana.com\/de\/wp-json\/wp\/v2\/media?parent=17887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/despensafranciscana.com\/de\/wp-json\/wp\/v2\/categories?post=17887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/despensafranciscana.com\/de\/wp-json\/wp\/v2\/tags?post=17887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}